{"id":293,"count":7,"description":"","link":"https:\/\/englobelaw.com\/fa\/category\/real-estate\/","name":"Real Estate","slug":"real-estate","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/englobelaw.com\/fa\/wp-json\/wp\/v2\/categories\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/englobelaw.com\/fa\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/englobelaw.com\/fa\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/englobelaw.com\/fa\/wp-json\/wp\/v2\/posts?categories=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}